{"id":1448,"date":"2016-06-29T19:19:51","date_gmt":"2016-06-29T19:19:51","guid":{"rendered":"http:\/\/turkseunie.be\/official\/?p=1448"},"modified":"2016-06-29T19:19:51","modified_gmt":"2016-06-29T19:19:51","slug":"bilgi-yarismasi","status":"publish","type":"post","link":"https:\/\/www.turkseunie.be\/official\/nl\/faaliyetlerimiz\/bilgi-yarismasi\/","title":{"rendered":"Quiz"},"content":{"rendered":"<p>Turkse Unie van Belgi&euml; vzw en T.I.K.E.V. organiseren in samenwerking met de Turkse Ambassade in Brussel Departement Onderwijs op 31 mei 2014 , de 2<sup>de<\/sup> finale van de Turkse Quiz Belgi&euml;.<\/p>\n<p>Iedereen is welkom op deze quiz. 36 kinderen van 12 verschillende regio&rsquo;s zullen quizzen.<\/p>\n<p><span style=\"font-size: medium;\"><strong>Datum: 31 mei 2014<\/strong><\/span><\/p>\n<p><strong>Uur: <\/strong>17u00<\/p>\n<p><strong>Plaats: <\/strong>Stadsschouwburg Genk<\/p>\n<p><strong>Adres: <\/strong>stadsplein 1, 3600 Genk<\/p>\n<p><strong>Inkom: <\/strong>Gratis<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Turkse Unie van Belgi&euml; vzw en T.I.K.E.V. organiseren in samenwerking met de Turkse Ambassade in Brussel Departement Onderwijs op 31 mei 2014 , de 2de finale van de Turkse Quiz Belgi&euml;. Iedereen is welkom op deze quiz. 36 kinderen van 12 verschillende regio&rsquo;s zullen quizzen. Datum: 31 mei 2014 Uur: 17u00 Plaats: Stadsschouwburg Genk Adres: [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2247,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,1,27,20],"tags":[],"post-meta-fields":{"_thumbnail_id":["2247"]},"_links":{"self":[{"href":"https:\/\/www.turkseunie.be\/official\/nl\/wp-json\/wp\/v2\/posts\/1448"}],"collection":[{"href":"https:\/\/www.turkseunie.be\/official\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.turkseunie.be\/official\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.turkseunie.be\/official\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.turkseunie.be\/official\/nl\/wp-json\/wp\/v2\/comments?post=1448"}],"version-history":[{"count":0,"href":"https:\/\/www.turkseunie.be\/official\/nl\/wp-json\/wp\/v2\/posts\/1448\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.turkseunie.be\/official\/nl\/wp-json\/wp\/v2\/media\/2247"}],"wp:attachment":[{"href":"https:\/\/www.turkseunie.be\/official\/nl\/wp-json\/wp\/v2\/media?parent=1448"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.turkseunie.be\/official\/nl\/wp-json\/wp\/v2\/categories?post=1448"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.turkseunie.be\/official\/nl\/wp-json\/wp\/v2\/tags?post=1448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}